{"id":5752,"date":"2024-10-03T19:10:04","date_gmt":"2024-10-03T17:10:04","guid":{"rendered":"https:\/\/lifecalma.com\/?page_id=5752"},"modified":"2025-06-15T22:16:10","modified_gmt":"2025-06-15T20:16:10","slug":"contact","status":"publish","type":"page","link":"https:\/\/lifecalma.com\/index.php\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"<header class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background fusion-parallax-none hundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-background-position:right center;--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:376px;--awb-padding-right:0px;--awb-padding-bottom:60px;--awb-padding-left:330px;--awb-padding-top-medium:242px;--awb-padding-right-medium:33px;--awb-padding-bottom-medium:191px;--awb-padding-left-medium:34px;--awb-padding-top-small:0px;--awb-padding-right-small:0px;--awb-padding-bottom-small:111px;--awb-padding-left-small:0px;--awb-margin-top:-8px;--awb-margin-bottom:0px;--awb-margin-bottom-small:0px;--awb-background-color:#f9f9f9;--awb-background-image:url(&quot;https:\/\/lifecalma.com\/wp-content\/uploads\/2024\/07\/contact-header1.avif&quot;);--awb-background-image-small:url(&#039;https:\/\/lifecalma.com\/wp-content\/uploads\/2024\/04\/sfondo-contact.avif&#039;);--awb-background-size:cover;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-justify-content-space-around fusion-flex-content-wrap\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_3 1_3 fusion-flex-column\" style=\"--awb-padding-top-medium:0px;--awb-padding-bottom-small:0px;--awb-padding-left-small:0px;--awb-bg-size:cover;--awb-width-large:33.333333333333%;--awb-margin-top-large:0px;--awb-spacing-right-large:5.76%;--awb-margin-bottom-large:134px;--awb-spacing-left-large:5.76%;--awb-width-medium:50%;--awb-order-medium:0;--awb-margin-top-medium:0px;--awb-spacing-right-medium:0%;--awb-margin-bottom-medium:0px;--awb-spacing-left-medium:7.296%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:0%;--awb-margin-bottom-small:1px;--awb-spacing-left-small:2.976%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1 md-text-align-left fusion-no-small-visibility\" style=\"--awb-content-alignment:center;--awb-user-select:none;\"><h1 style=\"font-size: 130px; --fontsize: 150; line-height: 156px; color: rgb(5, 38, 0); font-family: 'Custom font Siam Giants';\" data-fusion-font=\"true\" data-fontsize=\"150\" data-lineheight=\"180px\">Contact<\/h1>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_2 1_2 fusion-flex-column\" style=\"--awb-padding-top-small:0px;--awb-padding-bottom-small:0px;--awb-padding-left-small:0px;--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.84%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:3.84%;--awb-width-medium:50%;--awb-order-medium:0;--awb-spacing-right-medium:3.84%;--awb-spacing-left-medium:3.84%;--awb-width-small:100%;--awb-order-small:2;--awb-spacing-right-small:0%;--awb-margin-bottom-small:0px;--awb-spacing-left-small:0%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element sm-text-align-center fusion-no-medium-visibility fusion-no-large-visibility\" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none\"><img decoding=\"async\" width=\"267\" height=\"300\" title=\"arbre\" src=\"https:\/\/lifecalma.com\/wp-content\/uploads\/2024\/04\/arbre.avif\" alt class=\"img-responsive wp-image-2340\" srcset=\"https:\/\/lifecalma.com\/wp-content\/uploads\/2024\/04\/arbre-200x225.avif 200w, https:\/\/lifecalma.com\/wp-content\/uploads\/2024\/04\/arbre.avif 267w\" sizes=\"(max-width: 640px) 100vw, 267px\" \/><\/span><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_1 1_1 fusion-flex-column fusion-no-medium-visibility fusion-no-large-visibility\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:2.784%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-2\"><h1 data-fusion-font=\"true\" style=\"text-align: center; font-size: 180px; line-height: 132px; color: rgb(46, 44, 46);\">Contact<\/h1>\n<\/div><\/div><\/div><\/div><\/header><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-flex-container has-pattern-background has-mask-background fusion-parallax-none nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:130px;--awb-padding-right:0px;--awb-padding-bottom:100px;--awb-padding-left:0px;--awb-margin-top:0px;--awb-background-image:url(&quot;https:\/\/lifecalma.com\/wp-content\/uploads\/2024\/06\/campagna.avif&quot;);--awb-background-size:cover;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_1_3 1_3 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:33.333333333333%;--awb-margin-top-large:0px;--awb-spacing-right-large:5.76%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:5.76%;--awb-width-medium:33.333333333333%;--awb-order-medium:0;--awb-spacing-right-medium:5.76%;--awb-spacing-left-medium:5.76%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-4 fusion_builder_column_1_4 1_4 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:25%;--awb-margin-top-large:0px;--awb-spacing-right-large:7.68%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:7.68%;--awb-width-medium:25%;--awb-order-medium:0;--awb-spacing-right-medium:7.68%;--awb-spacing-left-medium:7.68%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-5 fusion_builder_column_1_4 1_4 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:25%;--awb-margin-top-large:0px;--awb-spacing-right-large:7.68%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:7.68%;--awb-width-medium:25%;--awb-order-medium:0;--awb-spacing-right-medium:7.68%;--awb-spacing-left-medium:7.68%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-6 fusion_builder_column_1_4 1_4 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:25%;--awb-margin-top-large:0px;--awb-spacing-right-large:7.68%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:7.68%;--awb-width-medium:25%;--awb-order-medium:0;--awb-spacing-right-medium:7.68%;--awb-spacing-left-medium:7.68%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-7 fusion_builder_column_1_2 1_2 fusion-flex-column\" style=\"--awb-overflow:hidden;--awb-bg-color:#bdd756;--awb-bg-color-hover:#bdd756;--awb-bg-size:cover;--awb-border-radius:100px 100px 100px 100px;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.84%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:3.84%;--awb-width-medium:50%;--awb-order-medium:0;--awb-spacing-right-medium:3.84%;--awb-spacing-left-medium:3.84%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:7.68%;--awb-spacing-left-small:7.776%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-3\" style=\"--awb-content-alignment:center;--awb-margin-top:30px;--awb-margin-right:30px;--awb-margin-left:30px;--awb-text-font-family:&quot;Lato&quot;;--awb-text-font-style:normal;--awb-text-font-weight:400;\"><p style=\"text-align: center; --fontsize: 30; line-height: 1.2;\"><span style=\"font-size: 22px;\" data-fusion-font=\"true\"><br \/>You are welcome <\/span><span style=\"font-size: 22px;\" data-fusion-font=\"true\">to contact me for any questions!<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 22px;\" data-fusion-font=\"true\"><b style=\"font-size: 25px;\" data-fusion-font=\"true\">For a Free 20 minutes <\/b><span style=\"color: #2e2c2e;\"><b><span style=\"font-size: 25px;\" data-fusion-font=\"true\">chat,<\/span><br \/><\/b><\/span><\/span><span style=\"background-color: var(--awb-bg-color-hover); color: var(--awb-text-color); font-family: var(--awb-text-font-family); font-size: 23px; font-style: var(--awb-text-font-style); font-weight: var(--awb-text-font-weight); letter-spacing: var(--awb-letter-spacing); text-align: var(--awb-content-alignment); text-transform: var(--awb-text-transform);\" data-fusion-font=\"true\">please read the 3 Steps below.<br \/><span style=\"color: var(--awb-custom_color_13);\">.<\/span><\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-8 fusion_builder_column_1_4 1_4 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:25%;--awb-margin-top-large:0px;--awb-spacing-right-large:7.68%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:7.68%;--awb-width-medium:25%;--awb-order-medium:0;--awb-spacing-right-medium:7.68%;--awb-spacing-left-medium:7.68%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-9 fusion_builder_column_1_3 1_3 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:33.333333333333%;--awb-margin-top-large:0px;--awb-spacing-right-large:5.76%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:5.76%;--awb-width-medium:33.333333333333%;--awb-order-medium:0;--awb-spacing-right-medium:5.76%;--awb-spacing-left-medium:5.76%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-10 fusion_builder_column_1_3 1_3 fusion-flex-column\" style=\"--awb-padding-left-medium:0px;--awb-bg-color:rgba(0,0,214,0);--awb-bg-color-hover:rgba(0,0,214,0);--awb-bg-size:cover;--awb-width-large:33.333333333333%;--awb-margin-top-large:0px;--awb-spacing-right-large:0%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:0%;--awb-width-medium:33.333333333333%;--awb-order-medium:0;--awb-spacing-right-medium:0%;--awb-spacing-left-medium:0%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:5.664%;--awb-spacing-left-small:6.24%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"accordian fusion-accordian\" style=\"margin-top:10px;margin-bottom:10px;--awb-margin-top:10px;--awb-margin-bottom:10px;--awb-padding-top:20px;--awb-padding-right:5px;--awb-padding-bottom:20px;--awb-padding-left:5px;--awb-border-size:1px;--awb-icon-size:16px;--awb-content-font-size:var(--awb-typography4-font-size);--awb-icon-alignment:right;--awb-hover-color:var(--awb-color1);--awb-border-color:#bdd756;--awb-background-color:#bdd756;--awb-divider-color:var(--awb-color8);--awb-divider-hover-color:var(--awb-color8);--awb-icon-color:var(--awb-color8);--awb-title-color:var(--awb-color8);--awb-content-color:var(--awb-color8);--awb-icon-box-color:var(--awb-color8);--awb-toggle-hover-accent-color:var(--awb-color8);--awb-toggle-active-accent-color:var(--awb-color8);--awb-title-font-family:&quot;Lato&quot;;--awb-title-font-weight:400;--awb-title-font-style:normal;--awb-title-font-size:16px;--awb-title-letter-spacing:var(--awb-typography1-letter-spacing);--awb-title-line-height:var(--awb-typography1-line-height);--awb-content-font-family:&quot;Lato&quot;;--awb-content-font-style:normal;--awb-content-font-weight:400;\"><div class=\"panel-group fusion-toggle-icon-right fusion-toggle-icon-unboxed\" id=\"accordion-5752-1\"><div class=\"fusion-panel panel-default panel-29c48d5fc705bcd1a fusion-toggle-no-divider fusion-toggle-boxed-mode\" style=\"--awb-content-font-size:13px;--awb-content-font-family:&quot;Lato&quot;;--awb-content-font-style:normal;--awb-content-font-weight:400;--awb-title-font-family:&quot;Lato&quot;;--awb-title-font-weight:400;--awb-title-font-style:normal;--awb-title-font-size:20px;\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_29c48d5fc705bcd1a\"><a aria-expanded=\"false\" aria-controls=\"29c48d5fc705bcd1a\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-5752-1\" data-target=\"#29c48d5fc705bcd1a\" href=\"#29c48d5fc705bcd1a\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon fa-ankh fas\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon fa-ankh fas\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Step 1 - Contact me<\/span><\/a><\/h4><\/div><div id=\"29c48d5fc705bcd1a\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_29c48d5fc705bcd1a\"><div class=\"panel-body toggle-content fusion-clearfix\">\r\n<p class=\"\"><strong style=\"font-size: 16px;\" data-fusion-font=\"true\">1. For<\/strong> <strong style=\"font-size: 16px;\" data-fusion-font=\"true\">any<\/strong> <strong><span style=\"font-size: 16px;\" data-fusion-font=\"true\">questions.<\/span><br \/><\/strong><span style=\"font-size: 16px;\" data-fusion-font=\"true\">You can contact me for any questions (contact form below).<\/span><\/p>\r\n<p class=\"\"><strong style=\"font-size: 16px;\" data-fusion-font=\"true\">2. To get<\/strong> <strong><span style=\"font-size: 16px;\" data-fusion-font=\"true\">your 20 minutes Free Chat.<\/span><br \/><\/strong><span style=\"font-size: 16px;\" data-fusion-font=\"true\">For this, please read further!<\/span><\/p>\r\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-f499154c7ea0f66ce fusion-toggle-no-divider fusion-toggle-boxed-mode\" style=\"--awb-content-font-size:16px;--awb-content-font-family:&quot;Lato&quot;;--awb-content-font-style:normal;--awb-content-font-weight:400;--awb-title-font-family:&quot;Lato&quot;;--awb-title-font-weight:400;--awb-title-font-style:normal;--awb-title-font-size:20px;\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_f499154c7ea0f66ce\"><a aria-expanded=\"false\" aria-controls=\"f499154c7ea0f66ce\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-5752-1\" data-target=\"#f499154c7ea0f66ce\" href=\"#f499154c7ea0f66ce\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon fa-ankh fas\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon fa-ankh fas\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Step 2 - Your Free 20 minutes chat<\/span><\/a><\/h4><\/div><div id=\"f499154c7ea0f66ce\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_f499154c7ea0f66ce\"><div class=\"panel-body toggle-content fusion-clearfix\"><p data-start=\"63\" data-end=\"159\">If you&#8217;re ready, for about 20 minutes, we\u2019ll exchange via WhatsApp or Telegram \u2014 through voice and text messages.<\/p>\n<p data-start=\"161\" data-end=\"264\">If after that, we feel there\u2019s a good connection, I\u2019ll send you a form to fill out so I can get to know you better.<\/p>\n<p data-start=\"266\" data-end=\"379\">Once we both agree to move forward, the coaching will begin as soon as I receive the payment for the first month.&nbsp;<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-11 fusion_builder_column_1_3 1_3 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:33.333333333333%;--awb-margin-top-large:0px;--awb-spacing-right-large:5.76%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:5.76%;--awb-width-medium:33.333333333333%;--awb-order-medium:0;--awb-spacing-right-medium:5.76%;--awb-spacing-left-medium:5.76%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-12 fusion_builder_column_1_3 1_3 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:33.333333333333%;--awb-margin-top-large:0px;--awb-spacing-right-large:5.76%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:5.76%;--awb-width-medium:33.333333333333%;--awb-order-medium:0;--awb-spacing-right-medium:5.76%;--awb-spacing-left-medium:5.76%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-13 fusion_builder_column_1_3 1_3 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:33.333333333333%;--awb-margin-top-large:0px;--awb-spacing-right-large:5.76%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:5.76%;--awb-width-medium:33.333333333333%;--awb-order-medium:0;--awb-spacing-right-medium:5.76%;--awb-spacing-left-medium:5.76%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-14 fusion_builder_column_1_3 1_3 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:33.333333333333%;--awb-margin-top-large:0px;--awb-spacing-right-large:5.76%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:5.76%;--awb-width-medium:33.333333333333%;--awb-order-medium:0;--awb-spacing-right-medium:5.76%;--awb-spacing-left-medium:5.76%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-3 fusion-flex-container has-pattern-background has-mask-background fusion-parallax-none nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-background-color:var(--awb-color3);--awb-background-image:url(&quot;https:\/\/lifecalma.com\/wp-content\/uploads\/2024\/06\/tramonto-colomba.avif&quot;);--awb-background-size:cover;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-15 fusion_builder_column_1_3 1_3 fusion-flex-column\" style=\"--awb-bg-color:var(--awb-custom_color_13);--awb-bg-color-hover:var(--awb-color1);--awb-bg-color-small:var(--awb-custom_color_13);--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-width-large:33.333333333333%;--awb-margin-top-large:30px;--awb-spacing-right-large:3.84%;--awb-margin-bottom-large:30px;--awb-spacing-left-large:5.76%;--awb-width-medium:33.333333333333%;--awb-order-medium:0;--awb-spacing-right-medium:3.84%;--awb-spacing-left-medium:5.76%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-16 fusion_builder_column_1_2 1_2 fusion-flex-column\" style=\"--awb-bg-color:rgba(216,216,216,0);--awb-bg-color-hover:color:#;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.84%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:3.84%;--awb-width-medium:50%;--awb-order-medium:0;--awb-spacing-right-medium:3.84%;--awb-spacing-left-medium:3.84%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-4\" style=\"--awb-text-font-family:&quot;Lato&quot;;--awb-text-font-style:normal;--awb-text-font-weight:400;\"><p><style id=\"wpforms-css-vars-root\">\n\t\t\t\t:root \n\t\t\t<\/style>\n<style id=\"wpforms-css-vars-3180-block-67042d26-2c5b-40f2-b914-19c5c340631e\">\n\t\t\t\t#wpforms-3180.wpforms-block-67042d26-2c5b-40f2-b914-19c5c340631e \n\t\t\t<\/style>\n<style id=\"wpforms-custom-css-3180-block-67042d26-2c5b-40f2-b914-19c5c340631e\">\n\t\t\t\tform nu003cformu003en  u003cinput name=u0022declared_firstu0022 value=u0022aboveu0022 \/u003en  u003cinput name=u0022declared_secondu0022 value=u0022belowu0022 \/u003enu003c\/formu003e\n\t\t\t<\/style>\n<style type=\"text\/css\">\n<p>\tbody #wpforms-3180 .wpforms-submit-container .wpforms-submit, body #wpforms-3180 .wpforms-field-pagebreak button.wpforms-page-button <\/p>\n<p>\tbody #wpforms-3180 .wpforms-submit-container .wpforms-submit:hover, body #wpforms-3180 .wpforms-field-pagebreak button.wpforms-page-button:hover <\/p>\n<p>\tbody #wpforms-3180 .wpforms-submit-container,\n\tbody #wpforms-3180 .wpforms-field-pagebreak .wpforms-pagebreak-left<\/p>\n<p>\tbody #wpforms-3180 .wpforms-form .wpforms-field label.wpforms-field-label,\n\tbody #wpforms-3180 .wpforms-form .wpforms-field .wpforms-field-label <\/p>\n<p>\/* Styling for Tablets *\/\n@media only screen and (max-width: 800px) and (min-width:481px) <\/p>\n<p>@media only screen and (max-width: 480px)\n\/*Option to add custom CSS *\/<\/p>\n<\/style>\n<div class=\"wpforms-container wpforms-container-full wpforms-inline-labels wp-form wpforms-block wpforms-block-67042d26-2c5b-40f2-b914-19c5c340631e wpf-right wpforms-render-modern\" id=\"wpforms-3180\">\n<form id=\"wpforms-form-3180\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"3180\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/index.php\/wp-json\/wp\/v2\/pages\/5752\" data-token=\"4152e754724f9053a1ea4ae1e2d8e1c5\" data-token-time=\"1788353495\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><\/p>\n<div class=\"wpforms-hidden\" id=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/div>\n<div class=\"wpforms-field-container\">\n<div id=\"wpforms-3180-field_1-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"1\">\n<fieldset>\n<legend class=\"wpforms-field-label\">Your name <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend>\n<div class=\"wpforms-field-row wpforms-field-medium\">\n<div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-3180-field_1\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][1][first]\" aria-errormessage=\"wpforms-3180-field_1-error\" required><label for=\"wpforms-3180-field_1\" class=\"wpforms-field-sublabel after\">First<\/label><\/div>\n<div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-3180-field_1-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][1][last]\" aria-errormessage=\"wpforms-3180-field_1-last-error\" required><label for=\"wpforms-3180-field_1-last\" class=\"wpforms-field-sublabel after\">Last<\/label><\/div>\n<\/div>\n<\/fieldset>\n<\/div>\n<div id=\"wpforms-3180-field_18-container\" class=\"wpforms-field wpforms-field-phone\" data-field-id=\"18\"><label class=\"wpforms-field-label\" for=\"wpforms-3180-field_18\">Your phone number <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"tel\" id=\"wpforms-3180-field_18\" class=\"wpforms-field-medium wpforms-field-required wpforms-smart-phone-field\" data-rule-smart-phone-field=\"true\" name=\"wpforms[fields][18]\" aria-label=\"Your phone number\" aria-errormessage=\"wpforms-3180-field_18-error\" required><\/div>\n<div id=\"wpforms-3180-field_15-container\" class=\"wpforms-field wpforms-field-select wpforms-conditional-trigger wpforms-field-select-style-modern\" data-field-id=\"15\"><label class=\"wpforms-field-label\" for=\"wpforms-3180-field_15\">Which MESSAGING APP do you use ? <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><select id=\"wpforms-3180-field_15\" class=\"wpforms-field-medium wpforms-field-required choicesjs-select\" data-size-class=\"wpforms-field-row wpforms-field-medium\" data-search-enabled=\"\" name=\"wpforms[fields][15]\" required=\"required\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'>WhatsApp<\/option><option value=\"WhatsApp\" >WhatsApp<\/option><option value=\"Telegram\" >Telegram<\/option><option value=\"Other\" >Other<\/option><\/select><\/div>\n<div id=\"wpforms-3180-field_9-container\" class=\"wpforms-field wpforms-field-text wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"9\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-3180-field_9\">Enter the application of your choice here <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-3180-field_9\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][9]\" aria-errormessage=\"wpforms-3180-field_9-error\" required><\/div>\n<div id=\"wpforms-3180-field_12-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"12\"><label class=\"wpforms-field-label\" for=\"wpforms-3180-field_12\">EMAIL  <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-3180-field_12\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][12]\" spellcheck=\"false\" aria-errormessage=\"wpforms-3180-field_12-error\" aria-describedby=\"wpforms-3180-field_12-description\" required><\/p>\n<div id=\"wpforms-3180-field_12-description\" class=\"wpforms-field-description\">In case i can't reach you by phone<\/div>\n<\/div>\n<div id=\"wpforms-3180-field_16-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"16\"><label class=\"wpforms-field-label\" for=\"wpforms-3180-field_16\">MESSAGE or QUESTION(S)<\/label><textarea id=\"wpforms-3180-field_16\" class=\"wpforms-field-medium\" name=\"wpforms[fields][16]\" aria-errormessage=\"wpforms-3180-field_16-error\" ><\/textarea><\/div>\n<div id=\"wpforms-3180-field_14-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"14\">\n<fieldset>\n<legend class=\"wpforms-field-label\">Are you ready for your 20 minutes Free Chat? <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend>\n<ul id=\"wpforms-3180-field_14\" class=\"wpforms-field-required\" data-choice-limit=\"1\">\n<li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-3180-field_14_2\" data-rule-check-limit=\"true\" name=\"wpforms[fields][14][]\" value=\"YES\" aria-errormessage=\"wpforms-3180-field_14_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-3180-field_14_2\">YES<\/label><\/li>\n<li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-3180-field_14_1\" data-rule-check-limit=\"true\" name=\"wpforms[fields][14][]\" value=\"Not yet\" aria-errormessage=\"wpforms-3180-field_14_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-3180-field_14_1\">Not yet<\/label><\/li>\n<\/ul>\n<\/fieldset>\n<\/div>\n<div id=\"wpforms-3180-field_20-container\" class=\"wpforms-field wpforms-field-gdpr-checkbox\" data-field-id=\"20\"><label class=\"wpforms-field-label\">GDPR Agreement <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><\/p>\n<ul id=\"wpforms-3180-field_20\" class=\"wpforms-field-required\">\n<li class=\"choice-1\"><input type=\"checkbox\" id=\"wpforms-3180-field_20_1\" name=\"wpforms[fields][20][]\" value=\"I consent to having this website store my submitted information so they can respond to my inquiry.\" aria-errormessage=\"wpforms-3180-field_20_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-3180-field_20_1\">I consent to having this website store my submitted information so they can respond to my inquiry.<\/label><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<p><!-- .wpforms-field-container --><\/p>\n<div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"3180\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/lifecalma.com\/index.php\/wp-json\/wp\/v2\/pages\/5752\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-3180\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\" Send my message\" aria-live=\"assertive\" value=\"wpforms-submit\"> Send my message<\/button><img decoding=\"async\" src=\"https:\/\/lifecalma.com\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div>\n<\/form>\n<\/div>\n<p>  <!-- .wpforms-container --><\/p>\n<\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"100-width.php","meta":{"footnotes":""},"class_list":["post-5752","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contact | LifeCalma<\/title>\n<meta name=\"description\" content=\"Coaching for women dealing with anxiety: psychology, breathing, spirituality, naturopathy, body moves, nutrition. Take control of your anxiety today!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lifecalma.com\/index.php\/contact\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contact | LifeCalma\" \/>\n<meta property=\"og:description\" content=\"Coaching for women dealing with anxiety: psychology, breathing, spirituality, naturopathy, body moves, nutrition. Take control of your anxiety today!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lifecalma.com\/index.php\/contact\/\" \/>\n<meta property=\"og:site_name\" content=\"LifeCalma\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-15T20:16:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lifecalma.com\/wp-content\/uploads\/2024\/06\/Miniature-contact.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Contact | LifeCalma\" \/>\n<meta name=\"twitter:description\" content=\"Coaching for women dealing with anxiety: psychology, breathing, spirituality, naturopathy, body moves, nutrition. Take control of your anxiety today!\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ContactPage\"],\"@id\":\"https:\\\/\\\/lifecalma.com\\\/index.php\\\/contact\\\/\",\"url\":\"https:\\\/\\\/lifecalma.com\\\/index.php\\\/contact\\\/\",\"name\":\"Contact | LifeCalma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lifecalma.com\\\/#website\"},\"datePublished\":\"2024-10-03T17:10:04+00:00\",\"dateModified\":\"2025-06-15T20:16:10+00:00\",\"description\":\"Coaching for women dealing with anxiety: psychology, breathing, spirituality, naturopathy, body moves, nutrition. Take control of your anxiety today!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lifecalma.com\\\/index.php\\\/contact\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lifecalma.com\\\/index.php\\\/contact\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lifecalma.com\\\/index.php\\\/contact\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lifecalma.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contact\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lifecalma.com\\\/#website\",\"url\":\"https:\\\/\\\/lifecalma.com\\\/\",\"name\":\"LifeCalma\",\"description\":\"Anxiety coaching for women by a woman. Holistic global approach.\",\"publisher\":{\"@id\":\"https:\\\/\\\/lifecalma.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lifecalma.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lifecalma.com\\\/#organization\",\"name\":\"LifeCalma\",\"url\":\"https:\\\/\\\/lifecalma.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lifecalma.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lifecalma.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-wordpress-square-100px-and-200px.png\",\"contentUrl\":\"https:\\\/\\\/lifecalma.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-wordpress-square-100px-and-200px.png\",\"width\":200,\"height\":200,\"caption\":\"LifeCalma\"},\"image\":{\"@id\":\"https:\\\/\\\/lifecalma.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contact | LifeCalma","description":"Coaching for women dealing with anxiety: psychology, breathing, spirituality, naturopathy, body moves, nutrition. Take control of your anxiety today!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lifecalma.com\/index.php\/contact\/","og_locale":"en_US","og_type":"article","og_title":"Contact | LifeCalma","og_description":"Coaching for women dealing with anxiety: psychology, breathing, spirituality, naturopathy, body moves, nutrition. Take control of your anxiety today!","og_url":"https:\/\/lifecalma.com\/index.php\/contact\/","og_site_name":"LifeCalma","article_modified_time":"2025-06-15T20:16:10+00:00","og_image":[{"width":600,"height":450,"url":"https:\/\/lifecalma.com\/wp-content\/uploads\/2024\/06\/Miniature-contact.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Contact | LifeCalma","twitter_description":"Coaching for women dealing with anxiety: psychology, breathing, spirituality, naturopathy, body moves, nutrition. Take control of your anxiety today!","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ContactPage"],"@id":"https:\/\/lifecalma.com\/index.php\/contact\/","url":"https:\/\/lifecalma.com\/index.php\/contact\/","name":"Contact | LifeCalma","isPartOf":{"@id":"https:\/\/lifecalma.com\/#website"},"datePublished":"2024-10-03T17:10:04+00:00","dateModified":"2025-06-15T20:16:10+00:00","description":"Coaching for women dealing with anxiety: psychology, breathing, spirituality, naturopathy, body moves, nutrition. Take control of your anxiety today!","breadcrumb":{"@id":"https:\/\/lifecalma.com\/index.php\/contact\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lifecalma.com\/index.php\/contact\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lifecalma.com\/index.php\/contact\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lifecalma.com\/"},{"@type":"ListItem","position":2,"name":"Contact"}]},{"@type":"WebSite","@id":"https:\/\/lifecalma.com\/#website","url":"https:\/\/lifecalma.com\/","name":"LifeCalma","description":"Anxiety coaching for women by a woman. Holistic global approach.","publisher":{"@id":"https:\/\/lifecalma.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lifecalma.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/lifecalma.com\/#organization","name":"LifeCalma","url":"https:\/\/lifecalma.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lifecalma.com\/#\/schema\/logo\/image\/","url":"https:\/\/lifecalma.com\/wp-content\/uploads\/2024\/03\/logo-wordpress-square-100px-and-200px.png","contentUrl":"https:\/\/lifecalma.com\/wp-content\/uploads\/2024\/03\/logo-wordpress-square-100px-and-200px.png","width":200,"height":200,"caption":"LifeCalma"},"image":{"@id":"https:\/\/lifecalma.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lifecalma.com\/index.php\/wp-json\/wp\/v2\/pages\/5752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lifecalma.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lifecalma.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lifecalma.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lifecalma.com\/index.php\/wp-json\/wp\/v2\/comments?post=5752"}],"version-history":[{"count":43,"href":"https:\/\/lifecalma.com\/index.php\/wp-json\/wp\/v2\/pages\/5752\/revisions"}],"predecessor-version":[{"id":6394,"href":"https:\/\/lifecalma.com\/index.php\/wp-json\/wp\/v2\/pages\/5752\/revisions\/6394"}],"wp:attachment":[{"href":"https:\/\/lifecalma.com\/index.php\/wp-json\/wp\/v2\/media?parent=5752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}